{"id":1066,"date":"2025-03-21T14:21:46","date_gmt":"2025-03-21T13:21:46","guid":{"rendered":"https:\/\/kine3terrassa.com\/fisioterapia\/tecnologia\/electrolisis-percutanea-intratisular\/"},"modified":"2026-07-20T11:56:38","modified_gmt":"2026-07-20T09:56:38","slug":"electrolisis-percutanea-intratisular","status":"publish","type":"page","link":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/","title":{"rendered":"Electr\u00f3lisis percut\u00e1nea intratisular"},"content":{"rendered":"[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; background_image=\u00bb485&#8243; background_image_position=\u00bbcenter center\u00bb background_image_stacking=\u00bbdefault\u00bb background_image_loading=\u00bbdefault\u00bb column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb250&#8243;][\/vc_column][vc_column column_padding=\u00bbpadding-7-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#ffffff\u00bb background_color_opacity=\u00bb0.6&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#0a0a0a\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb el_class=\u00bbheadingText\u00bb]\n<h1>ELECTR\u00d3LISIS PERCUT\u00c1NEA (EPI)<\/h1>\n[\/vc_column_text][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb el_class=\u00bbdescriptionMargin\u00bb]La electr\u00f3lisis percut\u00e1nea es una t\u00e9cnica de <a href=\"https:\/\/kine3terrassa.com\/es\/fisioterapia\/\">fisioterapia <\/a>invasiva, que ha sido una revoluci\u00f3n en el mundo de la fisioterapia deportiva y traumat\u00f2logica.<\/p>\n<h3><strong>Principales indicaciones:<\/strong><\/h3>\n[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-thin-line\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li>Roturas musculares<\/li>\n<li>Lesiones ligamentosas<\/li>\n<li>Tendinopaties<\/li>\n<\/ul>\n <\/div>[vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h2><strong>Que es la electr\u00f3lisis percut\u00e1nea?<\/strong><\/h2>\n<p>La Electr\u00f3lisis percut\u00e1nea consiste en la aplicaci\u00f3n de una corriente contin\u00faa, o tambi\u00e9n denominada, corriendo galv\u00e1nica, a trav\u00e9s de una aguja de punci\u00f3n seca.[\/vc_column_text][nectar_btn size=\u00bblarge\u00bb button_style=\u00bbregular\u00bb button_color_2=\u00bbExtra-Color-1&#8243; color_override=\u00bb#1CB0CA\u00bb solid_text_color_override=\u00bb#ffffff\u00bb icon_family=\u00bbnone\u00bb text=\u00bbPedir cita\u00bb url=\u00bb#contacte\u00bb margin_right=\u00bb15&#8243;][nectar_btn size=\u00bblarge\u00bb button_style=\u00bbregular\u00bb button_color_2=\u00bbExtra-Color-2&#8243; color_override=\u00bb#f26b24&#8243; solid_text_color_override=\u00bb#ffffff\u00bb icon_family=\u00bbnone\u00bb el_class=\u00bbveurepreu\u00bb text=\u00bbVer precio\u00bb url=\u00bb#preu\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbcolumn_reverse\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbpadding-7-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#f5f5f5&#8243; background_color_opacity=\u00bb0.6&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#0a0a0a\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb el_class=\u00bbdescriptionMargin\u00bb]\n<h2>C\u00f3mo funciona La electr\u00f3lisis percut\u00e1nea?<\/h2>\n<p>La aguja (qu\u00e9 act\u00faa de electrodo negativo) se introduce de manera eco guiada al tejido afectado(m\u00fasculo, tend\u00f3n, ligamento) produciendo un est\u00edmulo el\u00e9ctrico qu\u00e9 provoca una reacci\u00f3n de car\u00e1cter local y la consecuente recuperaci\u00f3n del tejido afectado.<\/p>\n<p>El proceso por el que una corriendo el\u00e9ctrica altera la estructura qu\u00edmica y separa los elementos de un compuesto reb el nombre de electr\u00f3lisis.<br \/>\nLa t\u00e9cnica aprovecha los principios de electr\u00f3lisis para conseguir una respuesta terap\u00e9utica.<\/p>\n<p>Los dispositivos de electr\u00f3lisis percut\u00e1nea terap\u00e9utica emiten y regulan la corriente galv\u00e1nica que se aplica sobre el tejido lisiado, con el objetivo de producir la electr\u00f3lisis y activar el proceso regenerativo que favorecen la recuperaci\u00f3n.[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; background_image=\u00bb484&#8243; background_image_position=\u00bbcenter center\u00bb background_image_stacking=\u00bbdefault\u00bb background_image_loading=\u00bbdefault\u00bb column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb250&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb50px\u00bb bottom_padding=\u00bb50px\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner left_padding_desktop=\u00bb25%\u00bb constrain_group_101=\u00bbyes\u00bb right_padding_desktop=\u00bb25%\u00bb left_padding_phone=\u00bb10px\u00bb constrain_group_105=\u00bbyes\u00bb right_padding_phone=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbadvanced\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h2 style=\"text-align: center;\">Precios de sesi\u00f3n de fisioterapia con electr\u00f3lisis percut\u00e1nea<\/h2>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=\u00bbyes\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-6-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#c2e4ea\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h3>Sesi\u00f3n de fisioterapia<\/h3>\n<p>Primera visita \u2014 65\u20ac<br \/>\nVisita continuada \u2014 55\u20ac[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-6-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#1CB0CA\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#ffffff\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h3>Pack de 5 sesiones<\/h3>\n<p>Precio por sesi\u00f3n \u2014 50\u20ac<br \/>\nPrecio total \u2014 250\u20ac[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-6-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#053c46&#8243; background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#ffffff\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h3>Pack de 10 sesiones<\/h3>\n<p>Precio por sesi\u00f3n \u2014 45\u20ac<br \/>\nPrecio total \u2014 450\u20ac[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner content_placement=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbcenter\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb css=\u00bb.vc_custom_1744113127525{background-color: #f5f5f5 !important;}\u00bb][vc_column_inner top_padding_desktop=\u00bb50px\u00bb bottom_padding_desktop=\u00bb50px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbadvanced\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h3 style=\"text-align: center;\">\u00bfQuieres empezar o saber m\u00e1s?<\/h3>\n[\/vc_column_text][nectar_btn size=\u00bblarge\u00bb button_style=\u00bbregular\u00bb button_color_2=\u00bbExtra-Color-2&#8243; color_override=\u00bb#f26b24&#8243; solid_text_color_override=\u00bb#ffffff\u00bb icon_family=\u00bbnone\u00bb text=\u00bbPedir informaci\u00f3n\u00bb url=\u00bb#contacte\u00bb margin_top=\u00bb15&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#f5f5f5&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb50px\u00bb bottom_padding=\u00bb50px\u00bb constrain_group_2=\u00bbyes\u00bb constrain_group_4=\u00bbyes\u00bb left_padding_phone=\u00bb10px\u00bb constrain_group_6=\u00bbyes\u00bb right_padding_phone=\u00bb10px\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb zindex=\u00bb10&#8243; overflow=\u00bbvisible\u00bb advanced_gradient_angle=\u00bb0&#8243; overlay_strength=\u00bb0.8&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbfast\u00bb shape_type=\u00bb\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h2 style=\"text-align: center;\">Preguntas frecuentes<\/h2>\n[\/vc_column_text][toggles style=\u00bbminimal_shadow\u00bb accordion=\u00bbtrue\u00bb accordion_starting_functionality=\u00bbclosed\u00bb border_radius=\u00bb20px\u00bb][toggle color=\u00bbDefault\u00bb heading_tag=\u00bbh3&#8243; heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfEs dolorosa?\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_min=\u00bb14px\u00bb font_size_max=\u00bb20px\u00bb font_size_desktop=\u00bb1.1vw\u00bb font_line_height=\u00bb1.6&#8243; text_direction=\u00bbdefault\u00bb]Se trata de una t\u00e9cnica m\u00ednimamente invasiva, si que nos puede ocasionar molestias pero tienen que ser soportables por el paciente. En funci\u00f3n de la lesi\u00f3n y zona a tratar se puede notar puntualmente cierta sensaci\u00f3n de ardor que tiene que ser del todo soportable.[\/nectar_responsive_text][\/toggle][toggle color=\u00bbDefault\u00bb heading_tag=\u00bbh3&#8243; heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfEs una t\u00e9cnica segura?\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_min=\u00bb14px\u00bb font_size_max=\u00bb20px\u00bb font_size_desktop=\u00bb1.1vw\u00bb font_line_height=\u00bb1.6&#8243; text_direction=\u00bbdefault\u00bb]Si. se realiza siempre de manera eco guiada para m\u00e1xima seguridad y eficiencia. se realiza siempre de manera eco guiada para m\u00e1xima seguridad y eficiencia.[\/nectar_responsive_text][\/toggle][toggle color=\u00bbDefault\u00bb heading_tag=\u00bbh3&#8243; heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfCu\u00e1les su las afectaciones m\u00e1s habituales que se tratan cono la electr\u00f3lisis?\u00bb]<div class=\"nectar-fancy-ul font_size_min_14px font_size_max_20px font_size_desktop_1-1vw font_line_height_1-6\" data-list-icon=\"dot\" data-animation=\"false\" data-animation-delay=\"0\" data-spacing=\"5px\" data-alignment=\"left\"> \n<ul>\n<li>Tendinopaties: Tendinitis rotuliana, tendinitis d\u2019aquiles, epitrocleitis, epicondilitis, tendinitis del supraespinos, tendinitis d\u2019espatlla(Infraespin\u00f3s, porci\u00f3 llarga del b\u00edceps, pectoral major.<\/li>\n<li>Roturas Musculares: Favorece el proceso de cicatrizaci\u00f3n.<\/li>\n<li>Esguinces cr\u00f3nicos: Efectos desfibrosante en lesiones de ligamentos de larga duraci\u00f3n que cursan con dolor.<\/li>\n<li>Meniscopat\u00edas: Para meniscitis (inflamaci\u00f3n meniscal).<\/li>\n<\/ul>\n <\/div>[\/toggle][toggle color=\u00bbDefault\u00bb heading_tag=\u00bbh3&#8243; heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfTengo que parar mi actividad deportiva o cotidiana mientras realizo el tratamiento?\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_min=\u00bb14px\u00bb font_size_max=\u00bb20px\u00bb font_size_desktop=\u00bb1.1vw\u00bb font_line_height=\u00bb1.6&#8243; text_direction=\u00bbdefault\u00bb]El reposo absoluto est\u00e1 totalmente contraindicado por lo general, pero s\u00ed es indispensable adaptar la carga de trabajo al tejido afectado para progresar en su recuperaci\u00f3n. El ejercicio terap\u00e9utico se vuelve clave en la recuperaci\u00f3n.<br \/>[\/nectar_responsive_text][\/toggle][toggle color=\u00bbDefault\u00bb heading_tag=\u00bbh3&#8243; heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfQu\u00e9 efectos fisiol\u00f3gicos tiene la electr\u00f3lisis?\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_min=\u00bb14px\u00bb font_size_max=\u00bb20px\u00bb font_size_desktop=\u00bb1.1vw\u00bb font_line_height=\u00bb1.6&#8243; text_direction=\u00bbdefault\u00bb]\n<ul>\n<li>Reduce la respuesta celular inlamatoria<\/li>\n<li>Modifica el pH y el potencial el\u00e9ctrico end\u00f3geno del tejido.<\/li>\n<li>Restablece el moviment de los fluidos dentro del medi extracelular<\/li>\n<li>Aumenta la diferenciaci\u00f3n, la migraci\u00f3n y la proliferaci\u00f3n de fagocitosis y de fenoblastos<\/li>\n<li>Disminuye las citocinas inflamatorias y los neurotransmisores nociceptives<\/li>\n<li>Activa las prote\u00ednas regenerativas del tend\u00f3n<\/li>\n<li>Estimula la s\u00edntesis de col\u00e1geno<\/li>\n<\/ul>\n[\/nectar_responsive_text][\/toggle][toggle color=\u00bbDefault\u00bb heading_tag=\u00bbh3&#8243; heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfPodr\u00e9 recuperarme s\u00f3lo haciendo la electr\u00f3lisis?\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_min=\u00bb14px\u00bb font_size_max=\u00bb20px\u00bb font_size_desktop=\u00bb1.1vw\u00bb font_line_height=\u00bb1.6&#8243; text_direction=\u00bbdefault\u00bb]No. El tratamiento de electr\u00f3lisis percut\u00e1nea en Terrassa que se realiza a Kine3, se hace de manera complementaria a la terapia activa(clave en tendinopat\u00edas), terapia manual, otra tecnolog\u00eda o ejercicio activo. Esto nos permite ser m\u00e1s eficientes y acelerar la recuperaci\u00f3n.[\/nectar_responsive_text][\/toggle][toggle color=\u00bbDefault\u00bb heading_tag=\u00bbh3&#8243; heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfCu\u00e1ntas sesiones de electr\u00f3lisis se necesitan?\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_min=\u00bb14px\u00bb font_size_max=\u00bb20px\u00bb font_size_desktop=\u00bb1.1vw\u00bb font_line_height=\u00bb1.6&#8243; text_direction=\u00bbdefault\u00bb]Acostumbran a hacer falta entre 2 y 4 sesiones por lesiones de moderada afectaci\u00f3n. En procesos muy agudos, se acostumbra a notar mucha mejora ya en la primera sesi\u00f3n.[\/nectar_responsive_text][\/toggle][toggle color=\u00bbDefault\u00bb heading_tag=\u00bbh3&#8243; heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfTiene contraindicaciones?\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_min=\u00bb14px\u00bb font_size_max=\u00bb20px\u00bb font_size_desktop=\u00bb1.1vw\u00bb font_line_height=\u00bb1.6&#8243; text_direction=\u00bbdefault\u00bb]En los siguientes estados se evitar\u00e1 el suyo os:<br \/>Infecciones, linfoedemas, alteraciones de la coagulaci\u00f3n, marcapasos, procesos oncol\u00f3gicos, embarazo.[\/nectar_responsive_text][\/toggle][toggle color=\u00bbDefault\u00bb heading_tag=\u00bbh3&#8243; heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfEn KINE3 trabaja con seguros privados?\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_min=\u00bb14px\u00bb font_size_max=\u00bb20px\u00bb font_size_desktop=\u00bb1.1vw\u00bb font_line_height=\u00bb1.6&#8243; text_direction=\u00bbdefault\u00bb]A KINE3 no trabajamos directamente con mutuas, pero si que puedes presentar nuestra factura que te haremos para que la mutua haga el copago. Depender\u00e1 del tipo de p\u00f3liza que tengas contratado. En el caso de que sea favorable, podr\u00e1s disfrutar de un tratamiento altamente especializado a precio de mutua: Tendr\u00e1s un fisioterapeuta con experiencia solo para t\u00fa durante 45-60\u2019, acceso en toda nuestra tecnolog\u00eda de Vanguardia de manera individual y a nuestro gimnasio completamente equipado.  <\/p>\n<p>Nuestra metodolog\u00eda de trabajo busca un tratamiento personalizado y la recuperaci\u00f3n m\u00e1s eficiente posible. Nos alejamos de un centro tradicional de mutuas con tratamientos grupales, protocolizados y no personalizados.[\/nectar_responsive_text][\/toggle][\/toggles][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1025,"parent":1058,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-1066","page","type-page","status-publish","has-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kine3 | Electr\u00f3lisis percut\u00e1nea (EPI) en Terrassa<\/title>\n<meta name=\"description\" content=\"Electr\u00f3lisis percut\u00e1nea intratisular (EPI) en Terrassa por tendinopat\u00edas y dolor cr\u00f3nico: tratamiento guiado por ecograf\u00eda y plan de recuperaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kine3 | Electr\u00f3lisis percut\u00e1nea (EPI) en Terrassa\" \/>\n<meta property=\"og:description\" content=\"Electr\u00f3lisis percut\u00e1nea intratisular (EPI) en Terrassa por tendinopat\u00edas y dolor cr\u00f3nico: tratamiento guiado por ecograf\u00eda y plan de recuperaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/\" \/>\n<meta property=\"og:site_name\" content=\"Kine3\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/KINE3\/61560753885986\/#\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T09:56:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kine3terrassa.com\/wp-content\/uploads\/2025\/07\/cropped-clinica_kine_03-removebg-preview-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/tecnologia\\\/electrolisis-percutanea-intratisular\\\/\",\"url\":\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/tecnologia\\\/electrolisis-percutanea-intratisular\\\/\",\"name\":\"Kine3 | Electr\u00f3lisis percut\u00e1nea (EPI) en Terrassa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/tecnologia\\\/electrolisis-percutanea-intratisular\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/tecnologia\\\/electrolisis-percutanea-intratisular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kine3terrassa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-clinica_kine_03-removebg-preview-1-1.png\",\"datePublished\":\"2025-03-21T13:21:46+00:00\",\"dateModified\":\"2026-07-20T09:56:38+00:00\",\"description\":\"Electr\u00f3lisis percut\u00e1nea intratisular (EPI) en Terrassa por tendinopat\u00edas y dolor cr\u00f3nico: tratamiento guiado por ecograf\u00eda y plan de recuperaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/tecnologia\\\/electrolisis-percutanea-intratisular\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/tecnologia\\\/electrolisis-percutanea-intratisular\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/tecnologia\\\/electrolisis-percutanea-intratisular\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kine3terrassa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-clinica_kine_03-removebg-preview-1-1.png\",\"contentUrl\":\"https:\\\/\\\/kine3terrassa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-clinica_kine_03-removebg-preview-1-1.png\",\"width\":512,\"height\":512,\"caption\":\"Kine 3 Fisioterapia i osteopatia Terrassa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/tecnologia\\\/electrolisis-percutanea-intratisular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tecnolog\u00eda\",\"item\":\"https:\\\/\\\/kine3terrassa.com\\\/es\\\/tecnologia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Electr\u00f3lisis percut\u00e1nea intratisular\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/#website\",\"url\":\"https:\\\/\\\/kine3terrassa.com\\\/\",\"name\":\"Kine3Terrassa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/#organization\"},\"alternateName\":\"Kine3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kine3terrassa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/#organization\",\"name\":\"Kine3\",\"url\":\"https:\\\/\\\/kine3terrassa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kine3terrassa.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/image-removebg-preview-2.png\",\"contentUrl\":\"https:\\\/\\\/kine3terrassa.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/image-removebg-preview-2.png\",\"width\":137,\"height\":56,\"caption\":\"Kine3\"},\"image\":{\"@id\":\"https:\\\/\\\/kine3terrassa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/KINE3\\\/61560753885986\\\/#\",\"https:\\\/\\\/www.instagram.com\\\/kine3_terrassa\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kine3\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kine3 | Electr\u00f3lisis percut\u00e1nea (EPI) en Terrassa","description":"Electr\u00f3lisis percut\u00e1nea intratisular (EPI) en Terrassa por tendinopat\u00edas y dolor cr\u00f3nico: tratamiento guiado por ecograf\u00eda y plan de recuperaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/","og_locale":"es_ES","og_type":"article","og_title":"Kine3 | Electr\u00f3lisis percut\u00e1nea (EPI) en Terrassa","og_description":"Electr\u00f3lisis percut\u00e1nea intratisular (EPI) en Terrassa por tendinopat\u00edas y dolor cr\u00f3nico: tratamiento guiado por ecograf\u00eda y plan de recuperaci\u00f3n.","og_url":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/","og_site_name":"Kine3","article_publisher":"https:\/\/www.facebook.com\/people\/KINE3\/61560753885986\/#","article_modified_time":"2026-07-20T09:56:38+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/kine3terrassa.com\/wp-content\/uploads\/2025\/07\/cropped-clinica_kine_03-removebg-preview-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/","url":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/","name":"Kine3 | Electr\u00f3lisis percut\u00e1nea (EPI) en Terrassa","isPartOf":{"@id":"https:\/\/kine3terrassa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/#primaryimage"},"image":{"@id":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/#primaryimage"},"thumbnailUrl":"https:\/\/kine3terrassa.com\/wp-content\/uploads\/2025\/07\/cropped-clinica_kine_03-removebg-preview-1-1.png","datePublished":"2025-03-21T13:21:46+00:00","dateModified":"2026-07-20T09:56:38+00:00","description":"Electr\u00f3lisis percut\u00e1nea intratisular (EPI) en Terrassa por tendinopat\u00edas y dolor cr\u00f3nico: tratamiento guiado por ecograf\u00eda y plan de recuperaci\u00f3n.","breadcrumb":{"@id":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/#primaryimage","url":"https:\/\/kine3terrassa.com\/wp-content\/uploads\/2025\/07\/cropped-clinica_kine_03-removebg-preview-1-1.png","contentUrl":"https:\/\/kine3terrassa.com\/wp-content\/uploads\/2025\/07\/cropped-clinica_kine_03-removebg-preview-1-1.png","width":512,"height":512,"caption":"Kine 3 Fisioterapia i osteopatia Terrassa"},{"@type":"BreadcrumbList","@id":"https:\/\/kine3terrassa.com\/es\/tecnologia\/electrolisis-percutanea-intratisular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/kine3terrassa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tecnolog\u00eda","item":"https:\/\/kine3terrassa.com\/es\/tecnologia\/"},{"@type":"ListItem","position":3,"name":"Electr\u00f3lisis percut\u00e1nea intratisular"}]},{"@type":"WebSite","@id":"https:\/\/kine3terrassa.com\/#website","url":"https:\/\/kine3terrassa.com\/","name":"Kine3Terrassa","description":"","publisher":{"@id":"https:\/\/kine3terrassa.com\/#organization"},"alternateName":"Kine3","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kine3terrassa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kine3terrassa.com\/#organization","name":"Kine3","url":"https:\/\/kine3terrassa.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kine3terrassa.com\/#\/schema\/logo\/image\/","url":"https:\/\/kine3terrassa.com\/wp-content\/uploads\/2025\/04\/image-removebg-preview-2.png","contentUrl":"https:\/\/kine3terrassa.com\/wp-content\/uploads\/2025\/04\/image-removebg-preview-2.png","width":137,"height":56,"caption":"Kine3"},"image":{"@id":"https:\/\/kine3terrassa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/KINE3\/61560753885986\/#","https:\/\/www.instagram.com\/kine3_terrassa","https:\/\/www.linkedin.com\/company\/kine3\/"]}]}},"_links":{"self":[{"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/pages\/1066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/comments?post=1066"}],"version-history":[{"count":8,"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/pages\/1066\/revisions"}],"predecessor-version":[{"id":1662,"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/pages\/1066\/revisions\/1662"}],"up":[{"embeddable":true,"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/pages\/1058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/media\/1025"}],"wp:attachment":[{"href":"https:\/\/kine3terrassa.com\/es\/wp-json\/wp\/v2\/media?parent=1066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}